{"id":1547,"date":"2026-07-08T04:05:15","date_gmt":"2026-07-08T04:05:15","guid":{"rendered":"https:\/\/getweaver.com\/?page_id=1547"},"modified":"2026-07-14T08:28:03","modified_gmt":"2026-07-14T08:28:03","slug":"industries","status":"publish","type":"page","link":"https:\/\/getweaver.com\/fr\/industries\/","title":{"rendered":"Industries"},"content":{"rendered":"<div class=\"bde-globalblock-1547-389 bde-globalblock\"><div class=\"bde-code-block-1173-100-1173-1 bde-code-block bde-code-block-1173-100\">\n\n  <div class=\"weaver-line-scene\">\n  <div class=\"dynamic-top-line-wrap\">\n    <div class=\"top-line-icon\">\n      <svg width=\"86\" height=\"85\" viewbox=\"0 0 86 85\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n        <g filter=\"url(#weaver_line_icon_filter)\">\n          <path d=\"M43 24C40.3766 37.875 38.2499 39.9456 24 42.5C38.25 45.0544 40.3766 47.125 43 61C45.6234 47.125 47.75 45.0544 62 42.5C47.75 39.9456 45.6233 37.875 43 24Z\" fill=\"white\"\/>\n        <\/g>\n        <defs>\n          <filter id=\"weaver_line_icon_filter\" x=\"0\" y=\"0\" width=\"86\" height=\"85\" filterunits=\"userSpaceOnUse\" color-interpolation-filters=\"sRGB\">\n            <feflood flood-opacity=\"0\" result=\"BackgroundImageFix\"\/>\n            <fecolormatrix in=\"SourceAlpha\" type=\"matrix\" values=\"0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 0 127 0\" result=\"hardAlpha\"\/>\n            <feoffset\/>\n            <fegaussianblur stddeviation=\"12\"\/>\n            <fecomposite in2=\"hardAlpha\" operator=\"out\"\/>\n            <fecolormatrix type=\"matrix\" values=\"0 0 0 0 1 0 0 0 0 1 0 0 0 0 1 0 0 0 0.5 0\"\/>\n            <feblend mode=\"normal\" in2=\"BackgroundImageFix\" result=\"effect1_dropShadow\"\/>\n            <feblend mode=\"normal\" in=\"SourceGraphic\" in2=\"effect1_dropShadow\" result=\"shape\"\/>\n          <\/filter>\n        <\/defs>\n      <\/svg>\n    <\/div>\n    <svg class=\"dynamic-top-line-svg\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" preserveaspectratio=\"none\">\n      <path class=\"dynamic-top-line-path\" fill=\"none\" stroke=\"white\" stroke-width=\"1.5\" opacity=\"0.2\"><\/path>\n    <\/svg>\n  <\/div>\n\n<div class=\"bottom-line-sg\">\n  <svg class=\"dynamic-bottom-line-sv\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" preserveaspectratio=\"none\">\n    <path class=\"dynamic-bottom-line-pat\" fill=\"none\" stroke=\"white\" stroke-width=\"1.5\" opacity=\"0.2\"><\/path>\n  <\/svg>\n<\/div>\n<\/div>\n\n\n<\/div><\/div><section class=\"bde-section-1547-105 bde-section\">\n  \n  \n\t\n\n\n\n<div class=\"section-container\"><div class=\"bde-div-1547-106 bde-div\">\n  \n  \n\t\n\n\n\n<h1 class=\"bde-heading-1547-107 bde-heading\">\nSecteurs d'activit\u00e9 avec lesquels nous travaillons\n<\/h1><div class=\"bde-text-1547-108 bde-text\">\nNous transformons les id\u00e9es complexes en strat\u00e9gies cibl\u00e9es, une ex\u00e9cution r\u00e9fl\u00e9chie et des r\u00e9sultats mesurables.\n<\/div>\n<\/div><div class=\"bde-icon-1547-109 bde-icon\" data-entrance=\"slideRight\">\n\n                \n            <div class=\"bde-icon-icon breakdance-icon-atom\" style=\"--eeiTransform: rotate(61deg);\">\n    \n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" fill=\"none\" viewbox=\"59.1 59.1 154.72 154.72\">\r\n<path d=\"M84.3658 162.406L84.3674 84.8054L84.3737 84.8054L110.074 110.506L110.074 162.407L84.3658 162.406Z\" fill=\"url(#paint0_linear_197_1034)\"\/>\r\n<path d=\"M84.373 84.8054L110.075 110.507L110.075 110.514H188.543L188.541 188.108L59.5748 188.106C62.1603 202.718 74.9192 213.814 90.2714 213.814L182.64 213.814C191.358 213.816 199.239 210.237 204.898 204.468C210.414 198.845 213.817 191.137 213.815 182.639V90.2707C213.815 88.4064 213.651 86.5799 213.338 84.8053L84.373 84.8054Z\" fill=\"url(#paint1_linear_197_1034)\"\/>\r\n<path d=\"M162.833 162.406L162.833 110.514L188.539 110.514L188.539 188.106L162.839 162.406L162.833 162.406Z\" fill=\"url(#paint2_linear_197_1034)\"\/>\r\n<path d=\"M183.043 59.0987C182.976 59.0971 182.909 59.0971 182.843 59.0971L90.2733 59.0971C81.5533 59.0971 73.6693 62.6761 68.0118 68.447C62.4976 74.0714 59.0981 81.7727 59.0981 90.2723L59.0965 182.639C59.0965 184.503 59.2619 186.332 59.5752 188.106L188.54 188.106L162.84 162.406H84.3655L84.3671 84.8054L84.3734 84.8054L213.338 84.8053C210.776 70.3239 198.218 59.2923 183.043 59.0987Z\" fill=\"url(#paint3_linear_197_1034)\"\/>\r\n<defs>\r\n<lineargradient id=\"paint0_linear_197_1034\" x1=\"98.6441\" y1=\"92.7554\" x2=\"95.5721\" y2=\"159.331\" gradientunits=\"userSpaceOnUse\">\r\n<stop stop-color=\"#004A80\"\/>\r\n<stop offset=\"1\" stop-color=\"#489FDF\"\/>\r\n<\/lineargradient>\r\n<lineargradient id=\"paint1_linear_197_1034\" x1=\"205.041\" y1=\"84.2306\" x2=\"78.3454\" y2=\"210.927\" gradientunits=\"userSpaceOnUse\">\r\n<stop stop-color=\"#48D597\"\/>\r\n<stop offset=\"1\" stop-color=\"#489FDF\"\/>\r\n<\/lineargradient>\r\n<lineargradient id=\"paint2_linear_197_1034\" x1=\"175.499\" y1=\"172.971\" x2=\"176.012\" y2=\"107.931\" gradientunits=\"userSpaceOnUse\">\r\n<stop stop-color=\"#004A80\"\/>\r\n<stop offset=\"1\" stop-color=\"#489FDF\"\/>\r\n<\/lineargradient>\r\n<lineargradient id=\"paint3_linear_197_1034\" x1=\"193.207\" y1=\"63.3453\" x2=\"80.6148\" y2=\"175.938\" gradientunits=\"userSpaceOnUse\">\r\n<stop stop-color=\"#A169DD\"\/>\r\n<stop offset=\"1\" stop-color=\"#E93CAC\"\/>\r\n<\/lineargradient>\r\n<\/defs>\r\n<\/svg>\n        \n        \n        \n            <\/div>\n    \n\n\n<\/div><\/div>\n<\/section><section id=\"startups\" class=\"bde-section-1547-197 bde-section\">\n  \n  \n\t\n\n\n\n<div class=\"section-container\"><h2 class=\"bde-heading-1547-198 bde-heading\">\nStartups et Scaleups\n<\/h2><div class=\"bde-text-1547-199 bde-text\">\nNous aidons les entreprises en phase de d\u00e9marrage et en pleine croissance \u00e0 construire les bases dont elles ont besoin pour lancer, d\u00e9velopper et faire \u00e9voluer leurs activit\u00e9s en toute confiance. De l'analyse de positionnement et de la strat\u00e9gie de mise sur le march\u00e9 \u00e0 la pr\u00e9paration aupr\u00e8s des investisseurs et \u00e0 la mise en place de syst\u00e8mes plus intelligents, nous accompagnons les entreprises dans leur passage de l'id\u00e9e \u00e0 la traction, et de la traction \u00e0 l'expansion.\n<\/div><div class=\"bde-advancedslider-1547-214 bde-advancedslider slider-custom-nav\">\n<div class=\"breakdance-swiper-wrapper\" data-swiper-id=\"214\">\n  <div class=\"swiper\">\n    <div class=\"swiper-wrapper\">\n      <div class=\"bde-advancedslide-1547-215 bde-advancedslide swiper-slide\"><div class=\"advanced-slider__slide\">\n  <div class=\"bde-div-1547-213 bde-div industries-card\">\n  \n  \n\t\n\n\n\n<h4 class=\"bde-heading-1547-207 bde-heading\">\nStartups en phase de d\u00e9marrage\n<\/h4><div class=\"bde-text-1547-208 bde-text\">\nPour les fondateurs qui d\u00e9veloppent leur marque, valident leur offre et se pr\u00e9parent \u00e0 entrer sur le march\u00e9.\n<\/div><img decoding=\"async\" class=\"bde-image2-1547-206 bde-image2 industry-card-img\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2026\/06\/square-angle-shape.svg\" loading=\"lazy\" sizes=\"(max-width: 168px) 100vw, 168px\">\n<\/div>\n<\/div><\/div><div class=\"bde-advancedslide-1547-235 bde-advancedslide swiper-slide\"><div class=\"advanced-slider__slide\">\n  <div class=\"bde-div-1547-236 bde-div industries-card\">\n  \n  \n\t\n\n\n\n<h4 class=\"bde-heading-1547-237 bde-heading\">\nEntreprises financ\u00e9es par capital-risque\n<\/h4><div class=\"bde-text-1547-238 bde-text\">\nPour les \u00e9quipes qui ont besoin d'un positionnement plus solide, de mat\u00e9riel pour investisseurs, de syst\u00e8mes \u00e9volutifs et d'un soutien \u00e0 la croissance.\n<\/div><img decoding=\"async\" class=\"bde-image2-1547-239 bde-image2 industry-card-img\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2026\/06\/triangle.svg\" loading=\"lazy\" sizes=\"(max-width: 187px) 100vw, 187px\">\n<\/div>\n<\/div><\/div><div class=\"bde-advancedslide-1547-230 bde-advancedslide swiper-slide\"><div class=\"advanced-slider__slide\">\n  <div class=\"bde-div-1547-231 bde-div industries-card\">\n  \n  \n\t\n\n\n\n<h4 class=\"bde-heading-1547-232 bde-heading\">\nEntreprises technologiques et SaaS\n<\/h4><div class=\"bde-text-1547-233 bde-text\">\nPour les entreprises vendant des produits num\u00e9riques, des plateformes, des outils ou des services bas\u00e9s sur la technologie.\n<\/div><img decoding=\"async\" class=\"bde-image2-1547-234 bde-image2 industry-card-img\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2026\/06\/pentagon.svg\" loading=\"lazy\" sizes=\"(max-width: 186px) 100vw, 186px\">\n<\/div>\n<\/div><\/div><div class=\"bde-advancedslide-1547-225 bde-advancedslide swiper-slide\"><div class=\"advanced-slider__slide\">\n  <div class=\"bde-div-1547-226 bde-div industries-card\">\n  \n  \n\t\n\n\n\n<h4 class=\"bde-heading-1547-227 bde-heading\">\nEntreprise ax\u00e9e sur l'innovation\n<\/h4><div class=\"bde-text-1547-228 bde-text\">\nPour les entreprises qui introduisent de nouvelles id\u00e9es, de nouveaux produits ou de nouveaux mod\u00e8les sur des march\u00e9s \u00e9tablis\n<\/div><img decoding=\"async\" class=\"bde-image2-1547-229 bde-image2 industry-card-img\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2026\/06\/lshape.svg\" loading=\"lazy\" sizes=\"(max-width: 168px) 100vw, 168px\">\n<\/div>\n<\/div><\/div>\n    <\/div>\n  <\/div>\n\n              <div class=\"swiper-button-prev\">\n            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"14\" viewbox=\"0 0 17 14\" fill=\"none\">\r\n<path d=\"M16.8867 6.70703H1.38672M7.38672 13.207L1.38672 6.70703L7.38672 0.707031\" stroke=\"#0C0C0C\" stroke-width=\"2\"\/>\r\n<\/svg>\n        <\/div>\n        <div class=\"swiper-button-next\">\n            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"14\" viewbox=\"0 0 17 14\" fill=\"none\">\r\n<path d=\"M0 6.70703H15.5M9.5 13.207L15.5 6.70703L9.5 0.707031\" stroke=\"#0C0C0C\" stroke-width=\"2\"\/>\r\n<\/svg>\n        <\/div>\n    \n    \n<\/div>\n\n<\/div><div class=\"bde-text-1547-240 bde-text\">\nNous aidons les entreprises en pleine croissance \u00e0 transformer leur \u00e9lan en une marque plus claire, des syst\u00e8mes plus solides et une voie plus cibl\u00e9e pour se d\u00e9velopper.\n<\/div><\/div>\n<\/section><section id=\"associations\" class=\"bde-section-1547-244 bde-section\">\n  \n  \n\t\n\n\n\n<div class=\"section-container\"><h2 class=\"bde-heading-1547-245 bde-heading\">\nAssociations et organisations membres\n<\/h2><div class=\"bde-text-1547-246 bde-text\">\nNous soutenons les associations, les chambres, les r\u00e9seaux de membres et les organisations communautaires avec une communication plus claire, un engagement plus fort et de meilleures exp\u00e9riences num\u00e9riques. Notre travail aide les organisations \u00e0 attirer des membres, \u00e0 servir leurs communaut\u00e9s, \u00e0 promouvoir des programmes et \u00e0 cr\u00e9er une valeur durable pour les personnes qu'elles repr\u00e9sentent.\n<\/div><div class=\"bde-advancedslider-1547-248 bde-advancedslider slider-custom-nav\">\n<div class=\"breakdance-swiper-wrapper\" data-swiper-id=\"248\">\n  <div class=\"swiper\">\n    <div class=\"swiper-wrapper\">\n      <div class=\"bde-advancedslide-1547-249 bde-advancedslide swiper-slide\"><div class=\"advanced-slider__slide\">\n  <div class=\"bde-div-1547-250 bde-div industries-card\">\n  \n  \n\t\n\n\n\n<h4 class=\"bde-heading-1547-251 bde-heading\">\nAssociations professionnelles\n<\/h4><div class=\"bde-text-1547-252 bde-text\">\nPour les organisations qui servent, \u00e9duquent et repr\u00e9sentent les professionnels dans un domaine sp\u00e9cifique.\n<\/div><img decoding=\"async\" class=\"bde-image2-1547-253 bde-image2 industry-card-img\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2026\/06\/square-angle-shape.svg\" loading=\"lazy\" sizes=\"(max-width: 168px) 100vw, 168px\">\n<\/div>\n<\/div><\/div><div class=\"bde-advancedslide-1547-254 bde-advancedslide swiper-slide\"><div class=\"advanced-slider__slide\">\n  <div class=\"bde-div-1547-255 bde-div industries-card\">\n  \n  \n\t\n\n\n\n<h4 class=\"bde-heading-1547-256 bde-heading\">\nChambres et r\u00e9seaux d'affaires\n<\/h4><div class=\"bde-text-1547-257 bde-text\">\nPour les groupes ax\u00e9s sur le d\u00e9veloppement commercial, la croissance locale, le r\u00e9seautage et l'engagement des membres.\n<\/div><img decoding=\"async\" class=\"bde-image2-1547-258 bde-image2 industry-card-img\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2026\/06\/triangle.svg\" loading=\"lazy\" sizes=\"(max-width: 187px) 100vw, 187px\">\n<\/div>\n<\/div><\/div><div class=\"bde-advancedslide-1547-259 bde-advancedslide swiper-slide\"><div class=\"advanced-slider__slide\">\n  <div class=\"bde-div-1547-260 bde-div industries-card\">\n  \n  \n\t\n\n\n\n<h4 class=\"bde-heading-1547-261 bde-heading\">\nOrganisations \u00e0 but non lucratif et organisations communautaires\n<\/h4><div class=\"bde-text-1547-262 bde-text\">\nPour les \u00e9quipes guid\u00e9es par une mission qui ont besoin d'un rayonnement, d'un storytelling et d'une communication am\u00e9lior\u00e9s avec les parties prenantes.\n<\/div><img decoding=\"async\" class=\"bde-image2-1547-263 bde-image2 industry-card-img\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2026\/06\/pentagon.svg\" loading=\"lazy\" sizes=\"(max-width: 186px) 100vw, 186px\">\n<\/div>\n<\/div><\/div><div class=\"bde-advancedslide-1547-264 bde-advancedslide swiper-slide\"><div class=\"advanced-slider__slide\">\n  <div class=\"bde-div-1547-265 bde-div industries-card\">\n  \n  \n\t\n\n\n\n<h4 class=\"bde-heading-1547-266 bde-heading\">\nOrganismes sectoriels et groupements professionnels\n<\/h4><div class=\"bde-text-1547-267 bde-text\">\nPour les organisations repr\u00e9sentant des secteurs, des priorit\u00e9s de plaidoyer ou des int\u00e9r\u00eats industriels communs.\n<\/div><img decoding=\"async\" class=\"bde-image2-1547-268 bde-image2 industry-card-img\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2026\/06\/lshape.svg\" loading=\"lazy\" sizes=\"(max-width: 168px) 100vw, 168px\">\n<\/div>\n<\/div><\/div>\n    <\/div>\n  <\/div>\n\n              <div class=\"swiper-button-prev\">\n            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"14\" viewbox=\"0 0 17 14\" fill=\"none\">\r\n<path d=\"M16.8867 6.70703H1.38672M7.38672 13.207L1.38672 6.70703L7.38672 0.707031\" stroke=\"#0C0C0C\" stroke-width=\"2\"\/>\r\n<\/svg>\n        <\/div>\n        <div class=\"swiper-button-next\">\n            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"14\" viewbox=\"0 0 17 14\" fill=\"none\">\r\n<path d=\"M0 6.70703H15.5M9.5 13.207L15.5 6.70703L9.5 0.707031\" stroke=\"#0C0C0C\" stroke-width=\"2\"\/>\r\n<\/svg>\n        <\/div>\n    \n    \n<\/div>\n\n<\/div><div class=\"bde-text-1547-272 bde-text\">\nNous aidons les organisations ax\u00e9es sur leurs membres \u00e0 communiquer leur valeur, \u00e0 renforcer l'engagement et \u00e0 cr\u00e9er des exp\u00e9riences plus claires pour les communaut\u00e9s qu'elles servent.\n<\/div><\/div>\n<\/section><section id=\"utilities\" class=\"bde-section-1547-273 bde-section\">\n  \n  \n\t\n\n\n\n<div class=\"section-container\"><h2 class=\"bde-heading-1547-274 bde-heading\">\n\u00c9nergie, Mines et Services publics\n<\/h2><div class=\"bde-text-1547-275 bde-text\">\nNous travaillons avec des organisations dans des secteurs complexes et essentiels o\u00f9 la clart\u00e9, la confiance et la communication avec les parties prenantes sont primordiales. Du storytelling technique \u00e0 la communication publique, en passant par les partenariats et les syst\u00e8mes op\u00e9rationnels, nous aidons \u00e0 communiquer la valeur de mani\u00e8re pr\u00e9cise, accessible et align\u00e9e sur la croissance \u00e0 long terme.\n<\/div><div class=\"bde-advancedslider-1547-277 bde-advancedslider slider-custom-nav\">\n<div class=\"breakdance-swiper-wrapper\" data-swiper-id=\"277\">\n  <div class=\"swiper\">\n    <div class=\"swiper-wrapper\">\n      <div class=\"bde-advancedslide-1547-278 bde-advancedslide swiper-slide\"><div class=\"advanced-slider__slide\">\n  <div class=\"bde-div-1547-279 bde-div industries-card\">\n  \n  \n\t\n\n\n\n<h4 class=\"bde-heading-1547-280 bde-heading\">\nSoci\u00e9t\u00e9s d'\u00e9nergie\n<\/h4><div class=\"bde-text-1547-281 bde-text\">\nPour les organisations qui op\u00e8rent sur les march\u00e9s de l'\u00e9nergie traditionnels, renouvelables, \u00e9mergents ou distribu\u00e9s.\n<\/div><img decoding=\"async\" class=\"bde-image2-1547-282 bde-image2 industry-card-img\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2026\/06\/square-angle-shape.svg\" loading=\"lazy\" sizes=\"(max-width: 168px) 100vw, 168px\">\n<\/div>\n<\/div><\/div><div class=\"bde-advancedslide-1547-283 bde-advancedslide swiper-slide\"><div class=\"advanced-slider__slide\">\n  <div class=\"bde-div-1547-284 bde-div industries-card\">\n  \n  \n\t\n\n\n\n<h4 class=\"bde-heading-1547-285 bde-heading\">\nEntreprises mini\u00e8res et de ressources\n<\/h4><div class=\"bde-text-1547-286 bde-text\">\nPour les entreprises qui communiquent des projets complexes, la valeur pour les parties prenantes et une croissance responsable.\n<\/div><img decoding=\"async\" class=\"bde-image2-1547-292 bde-image2 industry-card-img\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2026\/06\/pentagon.svg\" loading=\"lazy\" sizes=\"(max-width: 186px) 100vw, 186px\">\n<\/div>\n<\/div><\/div><div class=\"bde-advancedslide-1547-288 bde-advancedslide swiper-slide\"><div class=\"advanced-slider__slide\">\n  <div class=\"bde-div-1547-289 bde-div industries-card\">\n  \n  \n\t\n\n\n\n<h4 class=\"bde-heading-1547-290 bde-heading\">\nPrestataires de services publics et d'infrastructures\n<\/h4><div class=\"bde-text-1547-291 bde-text\">\nPour les prestataires de services essentiels g\u00e9rant la communication publique, les op\u00e9rations et la confiance des clients.\n<\/div><img decoding=\"async\" class=\"bde-image2-1547-287 bde-image2 industry-card-img\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2026\/06\/triangle.svg\" loading=\"lazy\" sizes=\"(max-width: 187px) 100vw, 187px\">\n<\/div>\n<\/div><\/div><div class=\"bde-advancedslide-1547-293 bde-advancedslide swiper-slide\"><div class=\"advanced-slider__slide\">\n  <div class=\"bde-div-1547-294 bde-div industries-card\">\n  \n  \n\t\n\n\n\n<h4 class=\"bde-heading-1547-295 bde-heading\">\nProjets CleanTech &amp; Innovation\n<\/h4><div class=\"bde-text-1547-296 bde-text\">\nPour les \u00e9quipes qui cr\u00e9ent de nouvelles technologies, des programmes de d\u00e9veloppement durable ou des solutions d'infrastructure ax\u00e9es sur l'avenir.\n<\/div><img decoding=\"async\" class=\"bde-image2-1547-297 bde-image2 industry-card-img\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2026\/06\/lshape.svg\" loading=\"lazy\" sizes=\"(max-width: 168px) 100vw, 168px\">\n<\/div>\n<\/div><\/div>\n    <\/div>\n  <\/div>\n\n              <div class=\"swiper-button-prev\">\n            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"14\" viewbox=\"0 0 17 14\" fill=\"none\">\r\n<path d=\"M16.8867 6.70703H1.38672M7.38672 13.207L1.38672 6.70703L7.38672 0.707031\" stroke=\"#0C0C0C\" stroke-width=\"2\"\/>\r\n<\/svg>\n        <\/div>\n        <div class=\"swiper-button-next\">\n            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"14\" viewbox=\"0 0 17 14\" fill=\"none\">\r\n<path d=\"M0 6.70703H15.5M9.5 13.207L15.5 6.70703L9.5 0.707031\" stroke=\"#0C0C0C\" stroke-width=\"2\"\/>\r\n<\/svg>\n        <\/div>\n    \n    \n<\/div>\n\n<\/div><div class=\"bde-text-1547-301 bde-text\">\nNous aidons les organisations de secteurs essentiels \u00e0 simplifier la compr\u00e9hension de travaux complexes, \u00e0 renforcer la confiance des parties prenantes et \u00e0 construire des voies de croissance plus solides.\n<\/div><\/div>\n<\/section><section id=\"government\" class=\"bde-section-1547-302 bde-section\">\n  \n  \n\t\n\n\n\n<div class=\"section-container\"><h2 class=\"bde-heading-1547-303 bde-heading\">\nGouvernement et secteur public\n<\/h2><div class=\"bde-text-1547-304 bde-text\">\nNous aidons les \u00e9quipes, programmes et initiatives du secteur public \u00e0 am\u00e9liorer la fa\u00e7on dont ils communiquent, engagent et diffusent des informations aux personnes qu'ils servent. Notre travail soutient une communication externe plus claire, un acc\u00e8s num\u00e9rique plus solide, de meilleurs syst\u00e8mes internes et une communication plus efficace entre les parties prenantes et les communaut\u00e9s.\n<\/div><div class=\"bde-advancedslider-1547-306 bde-advancedslider slider-custom-nav\">\n<div class=\"breakdance-swiper-wrapper\" data-swiper-id=\"306\">\n  <div class=\"swiper\">\n    <div class=\"swiper-wrapper\">\n      <div class=\"bde-advancedslide-1547-307 bde-advancedslide swiper-slide\"><div class=\"advanced-slider__slide\">\n  <div class=\"bde-div-1547-308 bde-div industries-card\">\n  \n  \n\t\n\n\n\n<h4 class=\"bde-heading-1547-309 bde-heading\">\nGouvernements municipaux\n<\/h4><div class=\"bde-text-1547-310 bde-text\">\nPour les gouvernements locaux qui ont besoin d'une communication plus claire, d'un meilleur acc\u00e8s num\u00e9rique et d'un engagement public renforc\u00e9.\n<\/div><img decoding=\"async\" class=\"bde-image2-1547-311 bde-image2 industry-card-img\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2026\/06\/square-angle-shape.svg\" loading=\"lazy\" sizes=\"(max-width: 168px) 100vw, 168px\">\n<\/div>\n<\/div><\/div><div class=\"bde-advancedslide-1547-312 bde-advancedslide swiper-slide\"><div class=\"advanced-slider__slide\">\n  <div class=\"bde-div-1547-313 bde-div industries-card\">\n  \n  \n\t\n\n\n\n<h4 class=\"bde-heading-1547-314 bde-heading\">\nOrganisations de d\u00e9veloppement \u00e9conomique\n<\/h4><div class=\"bde-text-1547-315 bde-text\">\nPour les \u00e9quipes soutenant l'attraction des entreprises, l'investissement, l'entrepreneuriat et la croissance r\u00e9gionale.\n<\/div><img decoding=\"async\" class=\"bde-image2-1547-316 bde-image2 industry-card-img\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2026\/06\/triangle.svg\" loading=\"lazy\" sizes=\"(max-width: 187px) 100vw, 187px\">\n<\/div>\n<\/div><\/div><div class=\"bde-advancedslide-1547-317 bde-advancedslide swiper-slide\"><div class=\"advanced-slider__slide\">\n  <div class=\"bde-div-1547-318 bde-div industries-card\">\n  \n  \n\t\n\n\n\n<h4 class=\"bde-heading-1547-319 bde-heading\">\nProgrammes et initiatives publics\n<\/h4><div class=\"bde-text-1547-320 bde-text\">\nPour les initiatives n\u00e9cessitant de la sensibilisation, de la promotion, des rapports et une communication accessible.\n<\/div><img decoding=\"async\" class=\"bde-image2-1547-321 bde-image2 industry-card-img\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2026\/06\/pentagon.svg\" loading=\"lazy\" sizes=\"(max-width: 186px) 100vw, 186px\">\n<\/div>\n<\/div><\/div><div class=\"bde-advancedslide-1547-322 bde-advancedslide swiper-slide\"><div class=\"advanced-slider__slide\">\n  <div class=\"bde-div-1547-323 bde-div industries-card\">\n  \n  \n\t\n\n\n\n<h4 class=\"bde-heading-1547-324 bde-heading\">\nOrganisations de l'\u00e9ducation et de la main-d'\u0153uvre\n<\/h4><div class=\"bde-text-1547-325 bde-text\">\nPour les organisations ax\u00e9es sur la formation, le d\u00e9veloppement de la main-d'\u0153uvre, les programmes pour les jeunes ou l'avancement communautaire.\n<\/div><img decoding=\"async\" class=\"bde-image2-1547-326 bde-image2 industry-card-img\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2026\/06\/lshape.svg\" loading=\"lazy\" sizes=\"(max-width: 168px) 100vw, 168px\">\n<\/div>\n<\/div><\/div>\n    <\/div>\n  <\/div>\n\n              <div class=\"swiper-button-prev\">\n            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"14\" viewbox=\"0 0 17 14\" fill=\"none\">\r\n<path d=\"M16.8867 6.70703H1.38672M7.38672 13.207L1.38672 6.70703L7.38672 0.707031\" stroke=\"#0C0C0C\" stroke-width=\"2\"\/>\r\n<\/svg>\n        <\/div>\n        <div class=\"swiper-button-next\">\n            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"14\" viewbox=\"0 0 17 14\" fill=\"none\">\r\n<path d=\"M0 6.70703H15.5M9.5 13.207L15.5 6.70703L9.5 0.707031\" stroke=\"#0C0C0C\" stroke-width=\"2\"\/>\r\n<\/svg>\n        <\/div>\n    \n    \n<\/div>\n\n<\/div><div class=\"bde-text-1547-330 bde-text\">\nNous aidons les organisations de secteurs essentiels \u00e0 simplifier la compr\u00e9hension de travaux complexes, \u00e0 renforcer la confiance des parties prenantes et \u00e0 construire des voies de croissance plus solides.\n<\/div><\/div>\n<\/section><section id=\"industrial\" class=\"bde-section-1547-331 bde-section\">\n  \n  \n\t\n\n\n\n<div class=\"section-container\"><h2 class=\"bde-heading-1547-332 bde-heading\">\nIndustriel et manufacturier\n<\/h2><div class=\"bde-text-1547-333 bde-text\">\nNous travaillons avec des entreprises industrielles et manufacturi\u00e8res pour communiquer leur valeur technique, renforcer leur pr\u00e9sence sur le march\u00e9 et soutenir leur croissance gr\u00e2ce \u00e0 des syst\u00e8mes plus clairs et des outils de vente plus performants. Du positionnement de marque \u00e0 l'am\u00e9lioration des flux de travail, nous aidons \u00e0 transformer l'expertise op\u00e9rationnelle en un avantage commercial plus visible et \u00e9volutif.\n<\/div><div class=\"bde-advancedslider-1547-335 bde-advancedslider slider-custom-nav\">\n<div class=\"breakdance-swiper-wrapper\" data-swiper-id=\"335\">\n  <div class=\"swiper\">\n    <div class=\"swiper-wrapper\">\n      <div class=\"bde-advancedslide-1547-336 bde-advancedslide swiper-slide\"><div class=\"advanced-slider__slide\">\n  <div class=\"bde-div-1547-337 bde-div industries-card\">\n  \n  \n\t\n\n\n\n<h4 class=\"bde-heading-1547-338 bde-heading\">\nFabricants\n<\/h4><div class=\"bde-text-1547-339 bde-text\">\nPour les entreprises produisant des biens, des composants, des mat\u00e9riaux ou des produits sp\u00e9cialis\u00e9s.\n<\/div><img decoding=\"async\" class=\"bde-image2-1547-340 bde-image2 industry-card-img\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2026\/06\/square-angle-shape.svg\" loading=\"lazy\" sizes=\"(max-width: 168px) 100vw, 168px\">\n<\/div>\n<\/div><\/div><div class=\"bde-advancedslide-1547-341 bde-advancedslide swiper-slide\"><div class=\"advanced-slider__slide\">\n  <div class=\"bde-div-1547-342 bde-div industries-card\">\n  \n  \n\t\n\n\n\n<h4 class=\"bde-heading-1547-343 bde-heading\">\nPrestataires de services industriels\n<\/h4><div class=\"bde-text-1547-344 bde-text\">\nPour les entreprises qui soutiennent les op\u00e9rations, la maintenance, la logistique, les services techniques ou le travail sur le terrain.\n<\/div><img decoding=\"async\" class=\"bde-image2-1547-345 bde-image2 industry-card-img\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2026\/06\/triangle.svg\" loading=\"lazy\" sizes=\"(max-width: 187px) 100vw, 187px\">\n<\/div>\n<\/div><\/div><div class=\"bde-advancedslide-1547-346 bde-advancedslide swiper-slide\"><div class=\"advanced-slider__slide\">\n  <div class=\"bde-div-1547-347 bde-div industries-card\">\n  \n  \n\t\n\n\n\n<h4 class=\"bde-heading-1547-348 bde-heading\">\nFournisseurs et distributeurs B2B\n<\/h4><div class=\"bde-text-1547-349 bde-text\">\nPour les entreprises qui ont besoin de supports de vente plus performants, d'une pr\u00e9sence num\u00e9rique renforc\u00e9e et d'une meilleure communication avec leurs acheteurs.\n<\/div><img decoding=\"async\" class=\"bde-image2-1547-350 bde-image2 industry-card-img\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2026\/06\/pentagon.svg\" loading=\"lazy\" sizes=\"(max-width: 186px) 100vw, 186px\">\n<\/div>\n<\/div><\/div><div class=\"bde-advancedslide-1547-351 bde-advancedslide swiper-slide\"><div class=\"advanced-slider__slide\">\n  <div class=\"bde-div-1547-352 bde-div industries-card\">\n  \n  \n\t\n\n\n\n<h4 class=\"bde-heading-1547-353 bde-heading\">\nEntreprises de fabrication de pointe\n<\/h4><div class=\"bde-text-1547-354 bde-text\">\nPour les entreprises utilisant l'automatisation, des processus sp\u00e9cialis\u00e9s ou de nouvelles technologies pour cro\u00eetre.\n<\/div><img decoding=\"async\" class=\"bde-image2-1547-355 bde-image2 industry-card-img\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2026\/06\/lshape.svg\" loading=\"lazy\" sizes=\"(max-width: 168px) 100vw, 168px\">\n<\/div>\n<\/div><\/div>\n    <\/div>\n  <\/div>\n\n              <div class=\"swiper-button-prev\">\n            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"14\" viewbox=\"0 0 17 14\" fill=\"none\">\r\n<path d=\"M16.8867 6.70703H1.38672M7.38672 13.207L1.38672 6.70703L7.38672 0.707031\" stroke=\"#0C0C0C\" stroke-width=\"2\"\/>\r\n<\/svg>\n        <\/div>\n        <div class=\"swiper-button-next\">\n            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"14\" viewbox=\"0 0 17 14\" fill=\"none\">\r\n<path d=\"M0 6.70703H15.5M9.5 13.207L15.5 6.70703L9.5 0.707031\" stroke=\"#0C0C0C\" stroke-width=\"2\"\/>\r\n<\/svg>\n        <\/div>\n    \n    \n<\/div>\n\n<\/div><div class=\"bde-text-1547-359 bde-text\">\nNous aidons les organisations de secteurs essentiels \u00e0 simplifier la compr\u00e9hension de travaux complexes, \u00e0 renforcer la confiance des parties prenantes et \u00e0 construire des voies de croissance plus solides.\n<\/div><\/div>\n<\/section><section id=\"construction\" class=\"bde-section-1547-360 bde-section\">\n  \n  \n\t\n\n\n\n<div class=\"section-container\"><h2 class=\"bde-heading-1547-361 bde-heading\">\nConstruction et Immobilier\n<\/h2><div class=\"bde-text-1547-362 bde-text\">\nNous aidons les organisations de construction, de d\u00e9veloppement et de immobilier \u00e0 \u00e9tablir la confiance, \u00e0 mettre en valeur la valeur des projets et \u00e0 cr\u00e9er des voies de croissance plus solides. Notre soutien couvre le positionnement de la marque, le storytelling de projet, la g\u00e9n\u00e9ration de prospects, l'exp\u00e9rience num\u00e9rique et les syst\u00e8mes qui aident les \u00e9quipes \u00e0 g\u00e9rer les opportunit\u00e9s plus efficacement.\n<\/div><div class=\"bde-advancedslider-1547-364 bde-advancedslider slider-custom-nav\">\n<div class=\"breakdance-swiper-wrapper\" data-swiper-id=\"364\">\n  <div class=\"swiper\">\n    <div class=\"swiper-wrapper\">\n      <div class=\"bde-advancedslide-1547-365 bde-advancedslide swiper-slide\"><div class=\"advanced-slider__slide\">\n  <div class=\"bde-div-1547-366 bde-div industries-card\">\n  \n  \n\t\n\n\n\n<h4 class=\"bde-heading-1547-367 bde-heading\">\nB\u00e2tisseurs et Entrepreneurs\n<\/h4><div class=\"bde-text-1547-368 bde-text\">\nPour les entreprises qui ont besoin de communiquer leur exp\u00e9rience, leur cr\u00e9dibilit\u00e9 et la qualit\u00e9 de leurs projets.\n<\/div><img decoding=\"async\" class=\"bde-image2-1547-369 bde-image2 industry-card-img\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2026\/06\/square-angle-shape.svg\" loading=\"lazy\" sizes=\"(max-width: 168px) 100vw, 168px\">\n<\/div>\n<\/div><\/div><div class=\"bde-advancedslide-1547-370 bde-advancedslide swiper-slide\"><div class=\"advanced-slider__slide\">\n  <div class=\"bde-div-1547-371 bde-div industries-card\">\n  \n  \n\t\n\n\n\n<h4 class=\"bde-heading-1547-372 bde-heading\">\nPromoteurs immobiliers\n<\/h4><div class=\"bde-text-1547-373 bde-text\">\nPour les \u00e9quipes qui lancent des projets sur le march\u00e9 et communiquent leur valeur aux acheteurs, locataires, investisseurs ou communaut\u00e9s.\n<\/div><img decoding=\"async\" class=\"bde-image2-1547-374 bde-image2 industry-card-img\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2026\/06\/triangle.svg\" loading=\"lazy\" sizes=\"(max-width: 187px) 100vw, 187px\">\n<\/div>\n<\/div><\/div><div class=\"bde-advancedslide-1547-375 bde-advancedslide swiper-slide\"><div class=\"advanced-slider__slide\">\n  <div class=\"bde-div-1547-376 bde-div industries-card\">\n  \n  \n\t\n\n\n\n<h4 class=\"bde-heading-1547-377 bde-heading\">\nGroupes de gestion immobili\u00e8re\n<\/h4><div class=\"bde-text-1547-378 bde-text\">\nPour les organisations qui g\u00e8rent la communication des locataires, les syst\u00e8mes num\u00e9riques et l'exp\u00e9rience de service.\n<\/div><img decoding=\"async\" class=\"bde-image2-1547-379 bde-image2 industry-card-img\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2026\/06\/pentagon.svg\" loading=\"lazy\" sizes=\"(max-width: 186px) 100vw, 186px\">\n<\/div>\n<\/div><\/div><div class=\"bde-advancedslide-1547-380 bde-advancedslide swiper-slide\"><div class=\"advanced-slider__slide\">\n  <div class=\"bde-div-1547-381 bde-div industries-card\">\n  \n  \n\t\n\n\n\n<h4 class=\"bde-heading-1547-382 bde-heading\">\n\u00c9quipes immobili\n<\/h4><div class=\"bde-text-1547-383 bde-text\">\nPour les entreprises ax\u00e9es sur la location, la vente, l'investissement, les partenariats ou la visibilit\u00e9 sur le march\u00e9.\n<\/div><img decoding=\"async\" class=\"bde-image2-1547-384 bde-image2 industry-card-img\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2026\/06\/lshape.svg\" loading=\"lazy\" sizes=\"(max-width: 168px) 100vw, 168px\">\n<\/div>\n<\/div><\/div>\n    <\/div>\n  <\/div>\n\n              <div class=\"swiper-button-prev\">\n            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"14\" viewbox=\"0 0 17 14\" fill=\"none\">\r\n<path d=\"M16.8867 6.70703H1.38672M7.38672 13.207L1.38672 6.70703L7.38672 0.707031\" stroke=\"#0C0C0C\" stroke-width=\"2\"\/>\r\n<\/svg>\n        <\/div>\n        <div class=\"swiper-button-next\">\n            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"14\" viewbox=\"0 0 17 14\" fill=\"none\">\r\n<path d=\"M0 6.70703H15.5M9.5 13.207L15.5 6.70703L9.5 0.707031\" stroke=\"#0C0C0C\" stroke-width=\"2\"\/>\r\n<\/svg>\n        <\/div>\n    \n    \n<\/div>\n\n<\/div><div class=\"bde-text-1547-388 bde-text\">\nNous aidons les organisations de secteurs essentiels \u00e0 simplifier la compr\u00e9hension de travaux complexes, \u00e0 renforcer la confiance des parties prenantes et \u00e0 construire des voies de croissance plus solides.\n<\/div><\/div>\n<\/section><section id=\"why-weaver\" class=\"bde-section-1547-179 bde-section\">\n  \n  \n\t\n\n\n\n<div class=\"section-container\"><h2 class=\"bde-heading-1547-180 bde-heading\">\nPourquoi Weaver ?\n<\/h2><div class=\"bde-icon-1547-181 bde-icon\" data-entrance=\"slideRight\">\n\n    \n            <div class=\"bde-icon-icon breakdance-icon-atom\" >\n    \n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"168\" height=\"261\" viewbox=\"0 0 168 261\" fill=\"none\">\r\n<path d=\"M84.4094 128.894L75.1272 144.974H16.0791C13.2066 144.974 10.4427 144.21 8.03711 142.82L16.0749 128.894L25.3613 112.815L89.2515 2.15796C96.9394 6.59658 99.5735 16.4276 95.1349 24.1169L43.9256 112.815L34.6435 128.894H84.4094Z\" fill=\"url(#paint0_linear_197_1055)\"\/>\r\n<path d=\"M89.2522 2.15802L25.362 112.815L16.0756 128.894L8.03778 142.82C5.63646 141.43 3.58787 139.421 2.15441 136.932C0.718138 134.448 0 131.674 0 128.899C0 126.136 0.709672 123.369 2.13889 120.889L2.15441 120.858L67.2891 8.04139C71.7277 0.353509 81.5587 -2.28483 89.2522 2.15802Z\" fill=\"url(#paint1_linear_197_1055)\"\/>\r\n<path d=\"M159.198 258.432L114.861 181.638L93.6907 144.973L84.4085 128.893H34.6426L43.9248 112.813H82.3599C89.3734 112.813 95.8493 116.554 99.354 122.625L165.084 236.467L165.108 236.511C169.516 244.196 166.874 253.999 159.198 258.43\" fill=\"url(#paint2_linear_197_1055)\"\/>\r\n<path d=\"M159.198 258.432C156.667 259.896 153.905 260.59 151.172 260.59C145.619 260.59 140.214 257.706 137.235 252.548L75.127 144.973L84.4091 128.893L93.6913 144.973L114.862 181.637L159.198 258.432Z\" fill=\"url(#paint3_linear_197_1055)\"\/>\r\n<defs>\r\n<lineargradient id=\"paint0_linear_197_1055\" x1=\"52.6646\" y1=\"151.831\" x2=\"52.6646\" y2=\"25.4502\" gradientunits=\"userSpaceOnUse\">\r\n<stop stop-color=\"#004A80\"\/>\r\n<stop offset=\"1\" stop-color=\"#489FDF\"\/>\r\n<\/lineargradient>\r\n<lineargradient id=\"paint1_linear_197_1055\" x1=\"72.2582\" y1=\"16.9765\" x2=\"0.548838\" y2=\"138.141\" gradientunits=\"userSpaceOnUse\">\r\n<stop stop-color=\"#48D597\"\/>\r\n<stop offset=\"1\" stop-color=\"#489FDF\"\/>\r\n<\/lineargradient>\r\n<lineargradient id=\"paint2_linear_197_1055\" x1=\"61.2941\" y1=\"111.044\" x2=\"107.452\" y2=\"196.766\" gradientunits=\"userSpaceOnUse\">\r\n<stop stop-color=\"#A169DD\"\/>\r\n<stop offset=\"1\" stop-color=\"#E93CAC\"\/>\r\n<\/lineargradient>\r\n<lineargradient id=\"paint3_linear_197_1055\" x1=\"75.1284\" y1=\"194.743\" x2=\"159.198\" y2=\"194.743\" gradientunits=\"userSpaceOnUse\">\r\n<stop stop-color=\"#48D597\"\/>\r\n<stop offset=\"1\" stop-color=\"#489FDF\"\/>\r\n<\/lineargradient>\r\n<\/defs>\r\n<\/svg>\n        \n        \n        \n            <\/div>\n    \n\n\n<\/div><div class=\"bde-animated-heading-1547-182 bde-animated-heading\">\n<h2 class=\"bde-animated-heading__text\">\n\t<span>Pas juste un autre<\/span>\n\n\t<span class=\"bde-animated-heading__wrapper\"><\/span>\n\n\n\n\t<span>soci\u00e9t\u00e9.<\/span>\n\n<\/h2>\n\n<noscript>\n      <h2 class=\"bde-animated-heading__noscript\">\n      <span>Pas juste un autre<\/span>\n      conception web\n      <span>soci\u00e9t\u00e9.<\/span>\n    <\/h2>\n      <h2 class=\"bde-animated-heading__noscript\">\n      <span>Pas juste un autre<\/span>\n      conception graphique\n      <span>soci\u00e9t\u00e9.<\/span>\n    <\/h2>\n      <h2 class=\"bde-animated-heading__noscript\">\n      <span>Pas juste un autre<\/span>\n      automatisation\n      <span>soci\u00e9t\u00e9.<\/span>\n    <\/h2>\n      <h2 class=\"bde-animated-heading__noscript\">\n      <span>Pas juste un autre<\/span>\n      image de marque\n      <span>soci\u00e9t\u00e9.<\/span>\n    <\/h2>\n  <\/noscript>\n<\/div><div class=\"bde-div-1547-183 bde-div\">\n  \n  \n\t\n\n\n\n<div class=\"bde-text-1547-184 bde-text\">\nNous ne sommes pas seulement un fournisseur de services. Weaver est un partenaire de croissance, vous aidant \u00e0 \u00e9laborer des strat\u00e9gies, des solutions cr\u00e9atives et les bonnes connexions. Gr\u00e2ce \u00e0 l'acc\u00e8s \u00e0 notre r\u00e9seau technologique \u00e9largi, nous ne nous contentons pas de fournir des r\u00e9sultats marketing ; nous vous aidons \u00e0 trouver de nouvelles opportunit\u00e9s pour financer, d\u00e9velopper et renforcer votre entreprise.\n<\/div><div class=\"bde-button-1547-185 bde-button styled-btn-1\">\n        \n    \n    \n    \n    \n            \n                    \n            \n            \n\n    \n    \n    \n    \n    \n    <a class=\"breakdance-link button-atom button-atom--primary bde-button__button\" href=\"\/fr\/contact\/\" target=\"_self\" data-type=\"url\"  >\n\n    \n        <span class=\"button-atom__text\">Commencer<\/span>\n\n                            \n        \n                <\/a>\n\n    \n\n\n<\/div>\n<\/div><\/div>\n<\/section><section id=\"clients\" class=\"bde-section-1547-186 bde-section\">\n  \n  \n\t\n\n\n\n<div class=\"section-container\"><div class=\"bde-text-1547-187 bde-text\" data-entrance=\"fade\">\nAdopt\u00e9 par les \u00e9quipes, des jeunes entreprises aux soci\u00e9t\u00e9s \u00e9tablies\n<\/div><div class=\"bde-globalblock-1547-188 bde-globalblock\"><div class=\"bde-logo-list-1081-100-1081-1 bde-logo-list logo-bar bde-logo-list-1081-100 gradient-overlay__both un-image-carousel-container\">\n\n  <div class=\"un-logo-bar__marquee-content carousel-type__stop-on-hover\">\n                            <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logos-mcancm.png\" width=\"555\" height=\"555\" srcset=\"https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logos-mcancm.png 555w, https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logos-mcancm-300x300.png 300w, https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logos-mcancm-150x150.png 150w\" sizes=\"auto, (max-width: 555px) 100vw, 555px\">\n        <\/div>\n                              <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logo-yyr.svg\" width=\"143\" height=\"53\" sizes=\"auto, (max-width: 143px) 100vw, 143px\">\n        <\/div>\n                              <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logo-evolve-white.svg\" width=\"2530\" height=\"472\" sizes=\"auto, (max-width: 2530px) 100vw, 2530px\">\n        <\/div>\n                              <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logo-checkpoint-white-big.png\" width=\"1600\" height=\"376\" srcset=\"https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logo-checkpoint-white-big.png 1600w, https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logo-checkpoint-white-big-300x71.png 300w, https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logo-checkpoint-white-big-1024x241.png 1024w, https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logo-checkpoint-white-big-768x180.png 768w, https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logo-checkpoint-white-big-1536x361.png 1536w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\">\n        <\/div>\n                              <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logo-windows-white.svg\" width=\"2532\" height=\"883\" sizes=\"auto, (max-width: 2532px) 100vw, 2532px\">\n        <\/div>\n                              <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logo-123paint-white.svg\" width=\"1184\" height=\"732\" sizes=\"auto, (max-width: 1184px) 100vw, 1184px\">\n        <\/div>\n                              <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logo-oaa-white.svg\" width=\"291\" height=\"134\" sizes=\"auto, (max-width: 291px) 100vw, 291px\">\n        <\/div>\n                              <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2026\/06\/Copy-of-Petroget-Logo-White-RGB.svg\" width=\"5000\" height=\"1040\" sizes=\"auto, (max-width: 5000px) 100vw, 5000px\">\n        <\/div>\n                                        <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logos-mcancm.png\" width=\"555\" height=\"555\" srcset=\"https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logos-mcancm.png 555w, https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logos-mcancm-300x300.png 300w, https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logos-mcancm-150x150.png 150w\" sizes=\"auto, (max-width: 555px) 100vw, 555px\">\n        <\/div>\n                              <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logo-yyr.svg\" width=\"143\" height=\"53\" sizes=\"auto, (max-width: 143px) 100vw, 143px\">\n        <\/div>\n                              <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logo-evolve-white.svg\" width=\"2530\" height=\"472\" sizes=\"auto, (max-width: 2530px) 100vw, 2530px\">\n        <\/div>\n                              <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logo-checkpoint-white-big.png\" width=\"1600\" height=\"376\" srcset=\"https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logo-checkpoint-white-big.png 1600w, https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logo-checkpoint-white-big-300x71.png 300w, https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logo-checkpoint-white-big-1024x241.png 1024w, https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logo-checkpoint-white-big-768x180.png 768w, https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logo-checkpoint-white-big-1536x361.png 1536w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\">\n        <\/div>\n                              <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logo-windows-white.svg\" width=\"2532\" height=\"883\" sizes=\"auto, (max-width: 2532px) 100vw, 2532px\">\n        <\/div>\n                              <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logo-123paint-white.svg\" width=\"1184\" height=\"732\" sizes=\"auto, (max-width: 1184px) 100vw, 1184px\">\n        <\/div>\n                              <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logo-oaa-white.svg\" width=\"291\" height=\"134\" sizes=\"auto, (max-width: 291px) 100vw, 291px\">\n        <\/div>\n                              <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2026\/06\/Copy-of-Petroget-Logo-White-RGB.svg\" width=\"5000\" height=\"1040\" sizes=\"auto, (max-width: 5000px) 100vw, 5000px\">\n        <\/div>\n                                        <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logos-mcancm.png\" width=\"555\" height=\"555\" srcset=\"https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logos-mcancm.png 555w, https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logos-mcancm-300x300.png 300w, https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logos-mcancm-150x150.png 150w\" sizes=\"auto, (max-width: 555px) 100vw, 555px\">\n        <\/div>\n                              <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logo-yyr.svg\" width=\"143\" height=\"53\" sizes=\"auto, (max-width: 143px) 100vw, 143px\">\n        <\/div>\n                              <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logo-evolve-white.svg\" width=\"2530\" height=\"472\" sizes=\"auto, (max-width: 2530px) 100vw, 2530px\">\n        <\/div>\n                              <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logo-checkpoint-white-big.png\" width=\"1600\" height=\"376\" srcset=\"https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logo-checkpoint-white-big.png 1600w, https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logo-checkpoint-white-big-300x71.png 300w, https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logo-checkpoint-white-big-1024x241.png 1024w, https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logo-checkpoint-white-big-768x180.png 768w, https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logo-checkpoint-white-big-1536x361.png 1536w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\">\n        <\/div>\n                              <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logo-windows-white.svg\" width=\"2532\" height=\"883\" sizes=\"auto, (max-width: 2532px) 100vw, 2532px\">\n        <\/div>\n                              <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logo-123paint-white.svg\" width=\"1184\" height=\"732\" sizes=\"auto, (max-width: 1184px) 100vw, 1184px\">\n        <\/div>\n                              <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logo-oaa-white.svg\" width=\"291\" height=\"134\" sizes=\"auto, (max-width: 291px) 100vw, 291px\">\n        <\/div>\n                              <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2026\/06\/Copy-of-Petroget-Logo-White-RGB.svg\" width=\"5000\" height=\"1040\" sizes=\"auto, (max-width: 5000px) 100vw, 5000px\">\n        <\/div>\n                                        <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logos-mcancm.png\" width=\"555\" height=\"555\" srcset=\"https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logos-mcancm.png 555w, https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logos-mcancm-300x300.png 300w, https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logos-mcancm-150x150.png 150w\" sizes=\"auto, (max-width: 555px) 100vw, 555px\">\n        <\/div>\n                              <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logo-yyr.svg\" width=\"143\" height=\"53\" sizes=\"auto, (max-width: 143px) 100vw, 143px\">\n        <\/div>\n                              <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logo-evolve-white.svg\" width=\"2530\" height=\"472\" sizes=\"auto, (max-width: 2530px) 100vw, 2530px\">\n        <\/div>\n                              <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logo-checkpoint-white-big.png\" width=\"1600\" height=\"376\" srcset=\"https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logo-checkpoint-white-big.png 1600w, https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logo-checkpoint-white-big-300x71.png 300w, https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logo-checkpoint-white-big-1024x241.png 1024w, https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logo-checkpoint-white-big-768x180.png 768w, https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logo-checkpoint-white-big-1536x361.png 1536w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\">\n        <\/div>\n                              <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logo-windows-white.svg\" width=\"2532\" height=\"883\" sizes=\"auto, (max-width: 2532px) 100vw, 2532px\">\n        <\/div>\n                              <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logo-123paint-white.svg\" width=\"1184\" height=\"732\" sizes=\"auto, (max-width: 1184px) 100vw, 1184px\">\n        <\/div>\n                              <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logo-oaa-white.svg\" width=\"291\" height=\"134\" sizes=\"auto, (max-width: 291px) 100vw, 291px\">\n        <\/div>\n                              <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2026\/06\/Copy-of-Petroget-Logo-White-RGB.svg\" width=\"5000\" height=\"1040\" sizes=\"auto, (max-width: 5000px) 100vw, 5000px\">\n        <\/div>\n                                        <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logos-mcancm.png\" width=\"555\" height=\"555\" srcset=\"https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logos-mcancm.png 555w, https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logos-mcancm-300x300.png 300w, https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logos-mcancm-150x150.png 150w\" sizes=\"auto, (max-width: 555px) 100vw, 555px\">\n        <\/div>\n                              <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logo-yyr.svg\" width=\"143\" height=\"53\" sizes=\"auto, (max-width: 143px) 100vw, 143px\">\n        <\/div>\n                              <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logo-evolve-white.svg\" width=\"2530\" height=\"472\" sizes=\"auto, (max-width: 2530px) 100vw, 2530px\">\n        <\/div>\n                              <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logo-checkpoint-white-big.png\" width=\"1600\" height=\"376\" srcset=\"https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logo-checkpoint-white-big.png 1600w, https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logo-checkpoint-white-big-300x71.png 300w, https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logo-checkpoint-white-big-1024x241.png 1024w, https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logo-checkpoint-white-big-768x180.png 768w, https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logo-checkpoint-white-big-1536x361.png 1536w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\">\n        <\/div>\n                              <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logo-windows-white.svg\" width=\"2532\" height=\"883\" sizes=\"auto, (max-width: 2532px) 100vw, 2532px\">\n        <\/div>\n                              <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logo-123paint-white.svg\" width=\"1184\" height=\"732\" sizes=\"auto, (max-width: 1184px) 100vw, 1184px\">\n        <\/div>\n                              <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logo-oaa-white.svg\" width=\"291\" height=\"134\" sizes=\"auto, (max-width: 291px) 100vw, 291px\">\n        <\/div>\n                              <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2026\/06\/Copy-of-Petroget-Logo-White-RGB.svg\" width=\"5000\" height=\"1040\" sizes=\"auto, (max-width: 5000px) 100vw, 5000px\">\n        <\/div>\n                                        <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logos-mcancm.png\" width=\"555\" height=\"555\" srcset=\"https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logos-mcancm.png 555w, https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logos-mcancm-300x300.png 300w, https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logos-mcancm-150x150.png 150w\" sizes=\"auto, (max-width: 555px) 100vw, 555px\">\n        <\/div>\n                              <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logo-yyr.svg\" width=\"143\" height=\"53\" sizes=\"auto, (max-width: 143px) 100vw, 143px\">\n        <\/div>\n                              <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logo-evolve-white.svg\" width=\"2530\" height=\"472\" sizes=\"auto, (max-width: 2530px) 100vw, 2530px\">\n        <\/div>\n                              <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logo-checkpoint-white-big.png\" width=\"1600\" height=\"376\" srcset=\"https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logo-checkpoint-white-big.png 1600w, https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logo-checkpoint-white-big-300x71.png 300w, https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logo-checkpoint-white-big-1024x241.png 1024w, https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logo-checkpoint-white-big-768x180.png 768w, https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logo-checkpoint-white-big-1536x361.png 1536w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\">\n        <\/div>\n                              <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logo-windows-white.svg\" width=\"2532\" height=\"883\" sizes=\"auto, (max-width: 2532px) 100vw, 2532px\">\n        <\/div>\n                              <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logo-123paint-white.svg\" width=\"1184\" height=\"732\" sizes=\"auto, (max-width: 1184px) 100vw, 1184px\">\n        <\/div>\n                              <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2025\/08\/logo-oaa-white.svg\" width=\"291\" height=\"134\" sizes=\"auto, (max-width: 291px) 100vw, 291px\">\n        <\/div>\n                              <div class=\"un-logo-bar__logo-wrapper\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2026\/06\/Copy-of-Petroget-Logo-White-RGB.svg\" width=\"5000\" height=\"1040\" sizes=\"auto, (max-width: 5000px) 100vw, 5000px\">\n        <\/div>\n                      <\/div>\n<\/div><\/div><\/div>\n<\/section><section id=\"cta\" class=\"bde-section-1547-189 bde-section weaver-anchor-section who-we-help-section\">\n  \n  \n\t\n\n\n\n<div class=\"section-container\"><div class=\"bde-icon-1547-190 bde-icon weaver-anchor-svg\">\n\n    \n            <div class=\"bde-icon-icon breakdance-icon-atom\" >\n    \n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"1920\" height=\"1622\" viewbox=\"0 0 1920 1622\" fill=\"none\">\r\n<g opacity=\"0.2\">\r\n<path id=\"bottom-anchor-mark\" data-anchor=\"bottom\" d=\"M701.061 1519.89C701.026 1519.96 700.993 1520.04 700.963 1520.12M700.963 1520.12C700.571 1521.16 700.702 1522.86 702.561 1522.39C704.561 1521.89 704.56 1520.39 703.561 1519.89C702.561 1519.39 702.061 1518.89 701.561 1519.39C701.137 1519.84 700.986 1520.06 700.963 1520.12Z\" stroke=\"#FB0A0A\"\/>\r\n<path d=\"M696.029 679.74V679.744V335.097L648.216 362.693L0 736.946V681.75\" stroke=\"white\" stroke-miterlimit=\"10\"\/>\r\n<path d=\"M1107.93 42.0874L1131.83 83.4789L743.82 307.497V652.148\" stroke=\"white\" stroke-miterlimit=\"10\"\/>\r\n<path d=\"M648.217 707.344V707.348V362.698\" stroke=\"white\" stroke-miterlimit=\"10\"\/>\r\n<path d=\"M1108 42.0834L0 681.683V626.488L1084.1 0.683105L1108 42.0834Z\" stroke=\"white\" stroke-miterlimit=\"10\"\/>\r\n<path d=\"M744.141 1090.58L1150.4 856.021\" stroke=\"white\" stroke-miterlimit=\"10\"\/>\r\n<path d=\"M1198.2 725.37V849.696C1198.2 870.689 1187 890.088 1168.82 900.581L791.941 1118.18\" stroke=\"white\" stroke-miterlimit=\"10\"\/>\r\n<path d=\"M696.336 789.967L433.491 941.725L385.678 914.117L1896.1 42.0874L1920 83.4789L1531.99 307.497\" stroke=\"white\" stroke-miterlimit=\"10\"\/>\r\n<path d=\"M696.345 1118.18L696.336 1118.17\" stroke=\"white\" stroke-miterlimit=\"10\"\/>\r\n<path d=\"M1484.19 335.093L744.141 762.363V1090.58\" stroke=\"white\" stroke-miterlimit=\"10\"\/>\r\n<path d=\"M1484.19 780.067V335.097\" stroke=\"white\" stroke-miterlimit=\"10\"\/>\r\n<path d=\"M1531.99 307.498V807.662\" stroke=\"white\" stroke-miterlimit=\"10\"\/>\r\n<path d=\"M1436.38 752.467V362.698\" stroke=\"white\" stroke-miterlimit=\"10\"\/>\r\n<path d=\"M1001.23 1294.2L696.344 1118.18L744.14 1090.58L1049.03 1266.62\" stroke=\"white\" stroke-miterlimit=\"10\"\/>\r\n<path d=\"M1144.64 1321.81L1436.37 1490.25\" stroke=\"white\" stroke-miterlimit=\"10\"\/>\r\n<path d=\"M1436.38 1545.44L1096.86 1349.41\" stroke=\"white\" stroke-miterlimit=\"10\"\/>\r\n<path d=\"M744.141 1035.37L1102.6 828.413\" stroke=\"white\" stroke-miterlimit=\"10\"\/>\r\n<path d=\"M1840.69 1041.1L1816.78 1082.49L1687.97 1008.12L1640.16 980.523H1640.15L1592.35 952.914H1592.34L1531.99 918.07L1484.19 890.47L1436.38 862.871L1198.2 725.37L1150.41 697.77V856.021L1102.6 828.413V642.571C1102.6 634.03 1104.88 625.812 1109 618.664\" stroke=\"white\" stroke-miterlimit=\"10\"\/>\r\n<path d=\"M1864.59 999.699L1840.69 1041.1L1109 618.664C1113.13 611.516 1119.11 605.435 1126.5 601.166C1133.9 596.894 1142.15 594.762 1150.4 594.762C1158.66 594.762 1166.91 596.894 1174.31 601.166L1864.59 999.699Z\" stroke=\"white\" stroke-miterlimit=\"10\"\/>\r\n<path d=\"M1531.99 918.07V1573.05C1531.99 1581.59 1529.71 1589.8 1525.59 1596.95C1521.46 1604.09 1515.49 1610.18 1508.1 1614.44C1500.7 1618.72 1492.45 1620.85 1484.19 1620.85V1125.77L1436.38 1153.38L1144.64 1321.81L1096.86 1349.41L1049.05 1377.01L726.383 1563.3L702.473 1521.89L1001.24 1349.41L1049.03 1321.81H1049.05L1096.83 1294.21L1436.38 1098.18L1484.19 1070.57\" stroke=\"white\" stroke-miterlimit=\"10\"\/>\r\n<path d=\"M1484.19 890.47L1484.18 1070.57\" stroke=\"white\" stroke-miterlimit=\"10\"\/>\r\n<path d=\"M702.468 1521.89L678.574 1480.49L1436.38 1042.97L1484.18 1070.56V1070.57\" stroke=\"white\" stroke-miterlimit=\"10\"\/>\r\n<path d=\"M1436.38 1042.97V862.87\" stroke=\"white\" stroke-miterlimit=\"10\"\/>\r\n<path d=\"M696.336 789.967V1118.17L696.344 1118.18\" stroke=\"white\" stroke-miterlimit=\"10\"\/>\r\n<path d=\"M953.423 1321.8L677.915 1162.74C659.733 1152.24 648.531 1132.84 648.531 1111.85V817.563\" stroke=\"white\" stroke-miterlimit=\"10\"\/>\r\n<path d=\"M1436.38 1545.44V1153.38\" stroke=\"white\" stroke-miterlimit=\"10\"\/>\r\n<path d=\"M1484.19 1620.85C1476.01 1620.85 1467.84 1618.76 1460.5 1614.57C1460.43 1614.53 1460.35 1614.49 1460.28 1614.45L1436.38 1600.64L1049.04 1377.01\" stroke=\"white\" stroke-miterlimit=\"10\"\/>\r\n<path d=\"M337.881 1044.77V920.425C337.881 909.932 340.676 899.842 345.746 891.058C350.606 882.63 357.565 875.403 366.148 870.199L1872.2 0.683105L1896.1 42.083\" stroke=\"white\" stroke-miterlimit=\"10\"\/>\r\n<path d=\"M433.49 941.725V1127.57C433.49 1136.11 431.211 1144.33 427.085 1151.47L385.681 1127.58L337.885 1099.98L99.7092 962.475L51.8962 934.863L4.09996 907.267L0.0078125 904.904V849.704L4.09996 852.067L51.8962 879.667L99.7092 907.267L337.885 1044.77L385.681 1072.37V914.117\" stroke=\"white\" stroke-miterlimit=\"10\"\/>\r\n<path d=\"M427.081 1151.47C422.955 1158.62 416.979 1164.7 409.579 1168.97C402.184 1173.24 393.928 1175.38 385.677 1175.38C377.425 1175.38 369.17 1173.24 361.775 1168.97L137.974 1039.76L0.00390625 960.113V904.904\" stroke=\"white\" stroke-miterlimit=\"10\"\/>\r\n<path id=\"top-anchor-mark\" data-anchor=\"top\" d=\"M1107 40.6832C1106.97 40.7536 1106.93 40.829 1106.9 40.9081M1106.9 40.9081C1106.51 41.9525 1106.64 43.648 1108.5 43.1832C1110.5 42.6832 1110.5 41.1832 1109.5 40.6832C1108.5 40.1832 1108 39.6832 1107.5 40.1832C1107.08 40.6319 1106.93 40.8534 1106.9 40.9081Z\" stroke=\"#FB0A0A\"\/>\r\n\r\n<circle class=\"top-line-anchor\" data-anchor=\"top-connect-point\" cx=\"1107.93\" cy=\"42.0874\" r=\"12\" fill=\"transparent\" pointer-events=\"all\"\/>\r\n<circle class=\"bottom-line-anchor\" data-anchor=\"bottom-connect-point\" cx=\"702.468\" cy=\"1521.89\" r=\"12\" fill=\"transparent\" pointer-events=\"all\"\/>\r\n<\/g>\r\n<\/svg>\n        \n        \n        \n            <\/div>\n    \n\n\n<\/div><div class=\"bde-globalblock-1547-191 bde-globalblock\"><div class=\"bde-div-1045-100-1045-1 bde-div bde-div-1045-100\">\n  \n  \n\t\n\n\n\n<h2 class=\"bde-heading-1045-101-1045-1 bde-heading bde-heading-1045-101\">\nVraies Voix. Vrais R\u00e9sultats.\n<\/h2><div class=\"bde-text-1045-102-1045-1 bde-text bde-text-1045-102\">\nDes gens avec qui nous travaillons\n<\/div><img decoding=\"async\" class=\"bde-image2-1045-103-1045-1 bde-image2 bde-image2-1045-103\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2026\/07\/weaver-strategic-company-c.png\" loading=\"lazy\" srcset=\"https:\/\/getweaver.com\/wp-content\/uploads\/2026\/07\/weaver-strategic-company-c.png 1614w, https:\/\/getweaver.com\/wp-content\/uploads\/2026\/07\/weaver-strategic-company-c-300x96.png 300w, https:\/\/getweaver.com\/wp-content\/uploads\/2026\/07\/weaver-strategic-company-c-1024x326.png 1024w, https:\/\/getweaver.com\/wp-content\/uploads\/2026\/07\/weaver-strategic-company-c-768x245.png 768w, https:\/\/getweaver.com\/wp-content\/uploads\/2026\/07\/weaver-strategic-company-c-1536x489.png 1536w, https:\/\/getweaver.com\/wp-content\/uploads\/2026\/07\/weaver-strategic-company-c-18x6.png 18w\" sizes=\"(max-width: 1614px) 100vw, 1614px\"><div class=\"bde-advancedslider-1045-104-1045-1 bde-advancedslider bde-advancedslider-1045-104\">\n<div class=\"breakdance-swiper-wrapper\" data-swiper-id=\"104\">\n  <div class=\"swiper\">\n    <div class=\"swiper-wrapper\">\n      <div class=\"bde-advancedslide-1045-105-1045-1 bde-advancedslide bde-advancedslide-1045-105 swiper-slide\"><div class=\"advanced-slider__slide\">\n  <div class=\"bde-simple-testimonial-1045-106-1045-1 bde-simple-testimonial bde-simple-testimonial-1045-106\">\n\n\n\n    \n                    \n    <div class='simple-testimonial__image-outer-wrapper simple-testimonial__standard-image simple-testimonial__standard-image--square'>\n                    <div class='simple-testimonial__image-inner-wrapper'>\n                <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2026\/06\/Group-39835.png\" width=\"126\" height=\"25\" sizes=\"auto, (max-width: 126px) 100vw, 126px\">\n            <\/div>\n            <\/div>\n\n\n\n    <div class='simple-testimonial__quote'>\n        <blockquote >\n            Beaucoup de cr\u00e9ativit\u00e9 et de connaissances dans nos initiatives de marketing num\u00e9rique. Fournir des contributions et une expertise pr\u00e9cieuses, tout en restant fid\u00e8le \u00e0 la vision et aux valeurs de notre entreprise. Fortement recommand\u00e9.\n        <\/blockquote>\n\n        \n    <\/div>\n\n\n    <div class='simple-testimonial__author' >\n        Cameron\n    <\/div>\n\n    <div class='simple-testimonial__author-info' >\n        Propri\u00e9taire, Acad\u00e9mie d'Acrobaties Osborne, Propri\u00e9taire\n    <\/div>\n\n\n\n<\/div>\n<\/div><\/div><div class=\"bde-advancedslide-1045-107-1045-1 bde-advancedslide bde-advancedslide-1045-107 swiper-slide\"><div class=\"advanced-slider__slide\">\n  <div class=\"bde-simple-testimonial-1045-108-1045-1 bde-simple-testimonial bde-simple-testimonial-1045-108\">\n\n\n\n    \n                    \n    <div class='simple-testimonial__image-outer-wrapper simple-testimonial__standard-image simple-testimonial__standard-image--square'>\n                    <div class='simple-testimonial__image-inner-wrapper'>\n                <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2026\/06\/Group-39835.png\" width=\"126\" height=\"25\" sizes=\"auto, (max-width: 126px) 100vw, 126px\">\n            <\/div>\n            <\/div>\n\n\n\n    <div class='simple-testimonial__quote'>\n        <blockquote >\n            Weaver nous a aid\u00e9s \u00e0 cr\u00e9er un site web qui raconte clairement notre histoire de durabilit\u00e9 et d'innovation d'une mani\u00e8re que nos clients appr\u00e9cient. Dan et son \u00e9quipe ont \u00e9galement apport\u00e9 des id\u00e9es cr\u00e9atives \u00e0 nos supports marketing, en gardant tout coh\u00e9rent avec notre marque tout en nous faisant gagner un temps pr\u00e9cieux. Hautement recommand\u00e9.\n        <\/blockquote>\n\n        \n    <\/div>\n\n\n    <div class='simple-testimonial__author' >\n        Andr\u00e9a\n    <\/div>\n\n    <div class='simple-testimonial__author-info' >\n        EVolveGrid, Directeur\n    <\/div>\n\n\n\n<\/div>\n<\/div><\/div><div class=\"bde-advancedslide-1045-109-1045-1 bde-advancedslide bde-advancedslide-1045-109 swiper-slide\"><div class=\"advanced-slider__slide\">\n  <div class=\"bde-simple-testimonial-1045-110-1045-1 bde-simple-testimonial bde-simple-testimonial-1045-110\">\n\n\n\n    \n                    \n    <div class='simple-testimonial__image-outer-wrapper simple-testimonial__standard-image simple-testimonial__standard-image--square'>\n                    <div class='simple-testimonial__image-inner-wrapper'>\n                <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2026\/06\/Group-39835.png\" width=\"126\" height=\"25\" sizes=\"auto, (max-width: 126px) 100vw, 126px\">\n            <\/div>\n            <\/div>\n\n\n\n    <div class='simple-testimonial__quote'>\n        <blockquote >\n            Nous avons commenc\u00e9 \u00e0 travailler avec Weaver lorsque nous avons eu besoin de trouver une nouvelle \u00e9quipe de conception de sites Web. Weaver nous a \u00e9t\u00e9 d'une grande aide pour r\u00e9cup\u00e9rer tous les fichiers et points d'acc\u00e8s n\u00e9cessaires afin de pr\u00e9server notre site Web professionnel et notre pr\u00e9sence en ligne. Par la suite, ils nous ont fourni des services de conseil pour examiner les options qui s'offraient \u00e0 nous pour d\u00e9velopper notre activit\u00e9 et rationaliser nos t\u00e2ches quotidiennes, ce qui a vraiment contribu\u00e9 \u00e0 redresser la situation pour nous. Excellent service, tr\u00e8s poli. Nous le recommandons sans h\u00e9siter.\n        <\/blockquote>\n\n        \n    <\/div>\n\n\n    <div class='simple-testimonial__author' >\n        Alex Testa\n    <\/div>\n\n    <div class='simple-testimonial__author-info' >\n        Marlex, PDG\n    <\/div>\n\n\n\n<\/div>\n<\/div><\/div><div class=\"bde-advancedslide-1045-111-1045-1 bde-advancedslide bde-advancedslide-1045-111 swiper-slide\"><div class=\"advanced-slider__slide\">\n  <div class=\"bde-simple-testimonial-1045-112-1045-1 bde-simple-testimonial bde-simple-testimonial-1045-112\">\n\n\n\n    \n                    \n    <div class='simple-testimonial__image-outer-wrapper simple-testimonial__standard-image simple-testimonial__standard-image--square'>\n                    <div class='simple-testimonial__image-inner-wrapper'>\n                <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2026\/06\/Group-39835.png\" width=\"126\" height=\"25\" sizes=\"auto, (max-width: 126px) 100vw, 126px\">\n            <\/div>\n            <\/div>\n\n\n\n    <div class='simple-testimonial__quote'>\n        <blockquote >\n            Choisir Weaver a sembl\u00e9 faire une diff\u00e9rence consid\u00e9rable pour nous. Leurs conseils nous ont vraiment aid\u00e9s \u00e0 cibler les meilleures strat\u00e9gies pour augmenter nos ventes gr\u00e2ce au marketing num\u00e9rique et \u00e0 l'automatisation. Leur \u00e9quipe a \u00e9t\u00e9 formidable pour nous guider tout au long du processus, de la planification \u00e0 la cr\u00e9ation de tous les supports dont nous avions besoin.<br>Je recommanderais vivement leurs services \u00e0 tous ceux qui veulent s\u00e9rieusement mettre leur entreprise sur la bonne voie !!!<br>\n        <\/blockquote>\n\n        \n    <\/div>\n\n\n    <div class='simple-testimonial__author' >\n        Jordanie \n    <\/div>\n\n    <div class='simple-testimonial__author-info' >\n        123 Peinture, Propri\u00e9taire\n    <\/div>\n\n\n\n<\/div>\n<\/div><\/div><div class=\"bde-advancedslide-1045-113-1045-1 bde-advancedslide bde-advancedslide-1045-113 swiper-slide\"><div class=\"advanced-slider__slide\">\n  <div class=\"bde-simple-testimonial-1045-114-1045-1 bde-simple-testimonial bde-simple-testimonial-1045-114\">\n\n\n\n    \n                    \n    <div class='simple-testimonial__image-outer-wrapper simple-testimonial__standard-image simple-testimonial__standard-image--square'>\n                    <div class='simple-testimonial__image-inner-wrapper'>\n                <img loading=\"lazy\" decoding=\"async\" class=\"breakdance-image-object\" src=\"https:\/\/getweaver.com\/wp-content\/uploads\/2026\/06\/Group-39835.png\" width=\"126\" height=\"25\" sizes=\"auto, (max-width: 126px) 100vw, 126px\">\n            <\/div>\n            <\/div>\n\n\n\n    <div class='simple-testimonial__quote'>\n        <blockquote >\n            J'ai travaill\u00e9 avec Jessica et Weaver sur un certain nombre de projets clients et le processus s'est toujours d\u00e9roul\u00e9 sans accroc. Ils fournissent un travail de qualit\u00e9 et sont faciles \u00e0 coordonner. Au plaisir de poursuivre notre collaboration !\n        <\/blockquote>\n\n        \n    <\/div>\n\n\n    <div class='simple-testimonial__author' >\n        Conor Hildebrandt\n    <\/div>\n\n\n\n\n<\/div>\n<\/div><\/div>\n    <\/div>\n  <\/div>\n\n      \n            <div class=\"swiper-pagination\"><\/div>\n    \n<\/div>\n\n<\/div>\n<\/div><\/div><div class=\"bde-div-1547-192 bde-div\">\n  \n  \n\t\n\n\n\n<div class=\"bde-div-1547-193 bde-div\">\n  \n  \n\t\n\n\n\n<div class=\"bde-icon-1547-194 bde-icon\" data-entrance=\"slideLeft\">\n\n                \n            <div class=\"bde-icon-icon breakdance-icon-atom\" style=\"--eeiTransform: rotate(8deg);\">\n    \n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" fill=\"none\" viewbox=\"59.1 59.1 154.72 154.72\">\r\n<path d=\"M84.3658 162.406L84.3674 84.8054L84.3737 84.8054L110.074 110.506L110.074 162.407L84.3658 162.406Z\" fill=\"url(#paint0_linear_197_1034)\"\/>\r\n<path d=\"M84.373 84.8054L110.075 110.507L110.075 110.514H188.543L188.541 188.108L59.5748 188.106C62.1603 202.718 74.9192 213.814 90.2714 213.814L182.64 213.814C191.358 213.816 199.239 210.237 204.898 204.468C210.414 198.845 213.817 191.137 213.815 182.639V90.2707C213.815 88.4064 213.651 86.5799 213.338 84.8053L84.373 84.8054Z\" fill=\"url(#paint1_linear_197_1034)\"\/>\r\n<path d=\"M162.833 162.406L162.833 110.514L188.539 110.514L188.539 188.106L162.839 162.406L162.833 162.406Z\" fill=\"url(#paint2_linear_197_1034)\"\/>\r\n<path d=\"M183.043 59.0987C182.976 59.0971 182.909 59.0971 182.843 59.0971L90.2733 59.0971C81.5533 59.0971 73.6693 62.6761 68.0118 68.447C62.4976 74.0714 59.0981 81.7727 59.0981 90.2723L59.0965 182.639C59.0965 184.503 59.2619 186.332 59.5752 188.106L188.54 188.106L162.84 162.406H84.3655L84.3671 84.8054L84.3734 84.8054L213.338 84.8053C210.776 70.3239 198.218 59.2923 183.043 59.0987Z\" fill=\"url(#paint3_linear_197_1034)\"\/>\r\n<defs>\r\n<lineargradient id=\"paint0_linear_197_1034\" x1=\"98.6441\" y1=\"92.7554\" x2=\"95.5721\" y2=\"159.331\" gradientunits=\"userSpaceOnUse\">\r\n<stop stop-color=\"#004A80\"\/>\r\n<stop offset=\"1\" stop-color=\"#489FDF\"\/>\r\n<\/lineargradient>\r\n<lineargradient id=\"paint1_linear_197_1034\" x1=\"205.041\" y1=\"84.2306\" x2=\"78.3454\" y2=\"210.927\" gradientunits=\"userSpaceOnUse\">\r\n<stop stop-color=\"#48D597\"\/>\r\n<stop offset=\"1\" stop-color=\"#489FDF\"\/>\r\n<\/lineargradient>\r\n<lineargradient id=\"paint2_linear_197_1034\" x1=\"175.499\" y1=\"172.971\" x2=\"176.012\" y2=\"107.931\" gradientunits=\"userSpaceOnUse\">\r\n<stop stop-color=\"#004A80\"\/>\r\n<stop offset=\"1\" stop-color=\"#489FDF\"\/>\r\n<\/lineargradient>\r\n<lineargradient id=\"paint3_linear_197_1034\" x1=\"193.207\" y1=\"63.3453\" x2=\"80.6148\" y2=\"175.938\" gradientunits=\"userSpaceOnUse\">\r\n<stop stop-color=\"#A169DD\"\/>\r\n<stop offset=\"1\" stop-color=\"#E93CAC\"\/>\r\n<\/lineargradient>\r\n<\/defs>\r\n<\/svg>\n        \n        \n        \n            <\/div>\n    \n\n\n<\/div><h2 class=\"bde-heading-1547-195 bde-heading text-indent-shape\">\nVotre prochaine \u00e9tape commence ici.\n<\/h2>\n<\/div><div class=\"bde-button-1547-196 bde-button styled-btn-1\">\n        \n    \n    \n    \n    \n            \n                    \n            \n            \n\n    \n    \n    \n    \n    \n    <a class=\"breakdance-link button-atom button-atom--primary bde-button__button\" href=\"\/fr\/contact\/\" target=\"_self\" data-type=\"url\"  >\n\n    \n        <span class=\"button-atom__text\">Commencer<\/span>\n\n        \n        \n                <\/a>\n\n    \n\n\n<\/div>\n<\/div><\/div>\n<\/section>","protected":false},"excerpt":{"rendered":"<p>Industries We Work With We turn complex ideas into focused strategies, thoughtful execution, and measurable results. Startups &#038; Scaleups We help early-stage and growing companies build the foundation they need to launch, grow, and scale with confidence. From positioning and go-to-market strategy to investor readiness and smarter systems, we support businesses moving from idea to [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_breakdance_hide_in_design_set":false,"_breakdance_tags":"","footnotes":""},"class_list":["post-1547","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/getweaver.com\/fr\/wp-json\/wp\/v2\/pages\/1547","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/getweaver.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/getweaver.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/getweaver.com\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/getweaver.com\/fr\/wp-json\/wp\/v2\/comments?post=1547"}],"version-history":[{"count":34,"href":"https:\/\/getweaver.com\/fr\/wp-json\/wp\/v2\/pages\/1547\/revisions"}],"predecessor-version":[{"id":1833,"href":"https:\/\/getweaver.com\/fr\/wp-json\/wp\/v2\/pages\/1547\/revisions\/1833"}],"wp:attachment":[{"href":"https:\/\/getweaver.com\/fr\/wp-json\/wp\/v2\/media?parent=1547"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}